{"id":31501,"date":"2024-06-23T21:14:17","date_gmt":"2024-06-23T21:14:17","guid":{"rendered":"https:\/\/ox-rud.com\/?p=31501"},"modified":"2025-11-20T08:25:14","modified_gmt":"2025-11-20T08:25:14","slug":"nuestro-balancin-separador-modular-m30-madrid","status":"publish","type":"post","link":"https:\/\/ox-rud.com\/es\/nuestro-balancin-separador-modular-m30-madrid\/","title":{"rendered":"Nuestro Balanc\u00edn Separador Modular en la M30 en Madrid"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb0&#8243; bottom_padding=\u00bb6%\u00bb left_padding_desktop=\u00bb5%\u00bb constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbpadding-10-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][split_line_heading animation_type=\u00bbdefault\u00bb text_direction=\u00bbdefault\u00bb el_class=\u00bbsofiasans\u00bb font_size=\u00bb70px\u00bb font_line_height=\u00bb0.9&#8243;]\n<h2><span style=\"color: #333333;\">Nuestro Balanc\u00edn separador modular <span style=\"color: #ff3b00;\">en la Autov\u00eda M30 de Madrid<\/span><\/span><\/h2>\n[\/split_line_heading][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][nectar_responsive_text font_size_desktop=\u00bb26px\u00bb font_size_tablet=\u00bb24px\u00bb font_size_phone=\u00bb22px\u00bb text_direction=\u00bbdefault\u00bb]Este caso de \u00e9xito refleja la capacidad de nuestra empresa para superar retos complejos mediante una planificaci\u00f3n detallada, el uso de tecnolog\u00edas avanzadas y una gesti\u00f3n log\u00edstica eficaz.<\/p>\n<p>La colaboraci\u00f3n con el equipo de <a href=\"https:\/\/gruasaguilar.com\/proyectos\/obras-publicas\/desmontaje-puente-nudo-m30\/\" target=\"_blank\" rel=\"noopener\">Gr\u00faas Aguilar<\/a> y la dedicaci\u00f3n de nuestro personal fueron claves para el \u00e9xito de la instalaci\u00f3n del puente prefabricado sobre la M30.[\/nectar_responsive_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][image_with_animation image_url=\u00bb24914&#8243; image_size=\u00bbfull\u00bb animation_type=\u00bbentrance\u00bb animation=\u00bbNone\u00bb animation_movement_type=\u00bbtransform_y\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bb\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbtop\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb6%\u00bb bottom_padding=\u00bb6%\u00bb left_padding_desktop=\u00bb5%\u00bb constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbno-extra-padding\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][nectar_responsive_text text_color=\u00bb#333333&#8243; font_size_desktop=\u00bb32px\u00bb font_size_tablet=\u00bb30px\u00bb font_line_height=\u00bb1.2&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb28px\u00bb]\n<h3>Antecedentes del proyecto<\/h3>\n[\/nectar_responsive_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb constrain_group_2=\u00bbyes\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbpadding-2-percent\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]En octubre de 2019, nuestra empresa recibi\u00f3 un encargo muy ambicioso: <strong>dise\u00f1ar y suministrar la ingenier\u00eda de elevaci\u00f3n para la instalaci\u00f3n de un puente de secciones prefabricadas sobre la autopista M30 en Madrid<\/strong>. Las secciones del puente pesaban hasta<strong> 300 toneladas<\/strong> y el proyecto requer\u00eda una entrega r\u00e1pida de vigas separadoras modulares para gr\u00faas y todos sus accesorios <strong>en el plazo de un mes<\/strong>.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbleft\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][nectar_responsive_text text_color=\u00bb#333333&#8243; font_size_desktop=\u00bb32px\u00bb font_size_tablet=\u00bb30px\u00bb font_line_height=\u00bb1.2&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb28px\u00bb]\n<h3>Desaf\u00edos<\/h3>\n[\/nectar_responsive_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]El proyecto present\u00f3 varios desaf\u00edos importantes:<\/p>\n<ul>\n<li><strong>Fabricaci\u00f3n r\u00e1pida<\/strong>: Necesit\u00e1bamos producir Balancines de elevaci\u00f3n y accesorios en un tiempo r\u00e9cord de un mes.<\/li>\n<li><strong>Eslingas especializadas<\/strong>: Las eslingas deb\u00edan encajar en orificios de 300 mm de di\u00e1metro y ser lo suficientemente flexibles y resistentes como para envolver las secciones de hormig\u00f3n sin da\u00f1arlas.<\/li>\n<li><strong>Materiales especiales<\/strong>: La necesidad de materiales pesados \u200b\u200by poco comunes complic\u00f3 a\u00fan m\u00e1s los plazos y los costes de entrega.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb3%\u00bb bottom_padding=\u00bb3%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbcenter\u00bb tablet_text_alignment=\u00bbcenter\u00bb phone_text_alignment=\u00bbcenter\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb.vc_custom_1716795183006{margin-bottom: 0px !important;padding-bottom: 0px !important;}\u00bb text_direction=\u00bbdefault\u00bb]<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28607 size-full aligncenter\" src=\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/05\/orange-line-200x20-1.png\" alt=\"\" width=\"200\" height=\"20\" \/>[\/vc_column_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb top_margin_tablet=\u00bb-10px\u00bb top_margin_phone=\u00bb-20px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][split_line_heading animation_type=\u00bbline-reveal-by-space\u00bb font_style=\u00bbh3&#8243; text_color=\u00bb#2c2c2c\u00bb line_reveal_by_space_text_effect=\u00bbdefault\u00bb content_alignment=\u00bbcenter\u00bb mobile_content_alignment=\u00bbcenter\u00bb link_target=\u00bb_self\u00bb text_content=\u00bbSoluciones aplicadas\u00bb text_direction=\u00bbdefault\u00bb][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbtop\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb3%\u00bb bottom_padding=\u00bb6%\u00bb left_padding_desktop=\u00bb5%\u00bb constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbno-extra-padding\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][nectar_responsive_text text_color=\u00bb#333333&#8243; font_size_desktop=\u00bb32px\u00bb font_size_tablet=\u00bb30px\u00bb font_line_height=\u00bb1.2&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb28px\u00bb]\n<h3>1. Balancines Separadores modulares para gr\u00faas<\/h3>\n[\/nectar_responsive_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb constrain_group_2=\u00bbyes\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbpadding-2-percent\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Se decidi\u00f3 utilizar los Balancines Separadores para gr\u00faas con formaci\u00f3n en cascada (como en la imagen). El plan de aparejo se desarroll\u00f3 mediante un montaje con <strong>3 Balancines Separadores modulares<\/strong>: en la parte superior, una unidad de <strong>400 toneladas de capacidad, modelo OX-SB-250\/400<\/strong> y en la parte inferior, <strong>dos Balancines Separadores inferiores de 170 toneladas de capacidad cada una, modelo OX-SB-170.<\/strong><\/p>\n<p><strong>Los <a href=\"https:\/\/ox-rud.com\/es\/productos\/balancin-de-carga-para-gruas\/\" target=\"_blank\" rel=\"noopener\">Balancines Separadores<\/a> para elevaci\u00f3n son uno de nuestros productos m\u00e1s vendidos y valorados<\/strong>\u00a0junto con la <a href=\"https:\/\/ox-rud.com\/es\/productos\/balancin-de-elevacion\/\" target=\"_blank\" rel=\"noopener\"><strong><u>gama de Balancines de Elevaci\u00f3n<\/u><\/strong><\/a>, que nos consultan en todo el mundo y que tambi\u00e9n son<\/p>\n<p><strong>\u00a1Actualmente tenemos los modelos con m\u00e1s capacidad total y m\u00e1s longitud de la Uni\u00f3n Europea! Desde 9 hasta 1350 toneladas de capacidad. Estamos acreditados por el Certificado DNV<\/strong> y el <strong>FEM-AEM<\/strong>. Tambi\u00e9n contamos con la <strong>ISO\u00a09001:2015<\/strong> y la <strong>ISO\u00a03834-2<\/strong>.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbleft\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_responsive_text text_color=\u00bb#333333&#8243; font_size_desktop=\u00bb32px\u00bb font_size_tablet=\u00bb30px\u00bb font_line_height=\u00bb1.2&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb28px\u00bb]\n<h3>2. Principales accesorios de elevaci\u00f3n<\/h3>\n[\/nectar_responsive_text][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>Otro requisito clave era que las eslingas inferiores deb\u00edan introducirse en agujeros de 300 mm de di\u00e1metro<\/strong> y ser lo suficientemente flexibles y resistentes como para abrazar la secci\u00f3n del puente por la base, sin da\u00f1arse ni a ellas mismas ni al hormig\u00f3n, pero estos son materiales de gran tonelaje no demasiado comunes y todos encarecen el proyecto.<\/p>\n<p>La soluci\u00f3n elegida fue utilizar eslingas especiales de <strong><a href=\"https:\/\/www.dsm.com\/products\/dyneema\/es_ES\/home.html?WT.srch=1&amp;WT.mc_id=SEA___&amp;gclid=CjwKCAiA1rPyBRAREiwA1UIy8Ht5yvXpPJLZOSDF-GiKa0avfRH7RTxdzCz2L3Iw-c_HlZdwF9YglRoC2hsQAvD_BwE\">Dyneema<\/a>, un material <strong>ultraresistente y muy ligero<\/strong>, con un <strong>peso aproximado de tan solo 100 kg por eslinga<\/strong> y un <strong>di\u00e1metro de 110 mm<\/strong> para elevar cada tramo del puente mediante dos unidades en cesta, en <strong>forma de \u201cU\u201d (como en la imagen)<\/strong>, con una capacidad resultante <strong>de 200 toneladas por <a href=\"https:\/\/en.wikipedia.org\/wiki\/Sling\">eslinga<\/a><\/strong>.<\/strong>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbtop\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb3%\u00bb bottom_padding=\u00bb6%\u00bb left_padding_desktop=\u00bb5%\u00bb constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbno-extra-padding\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][nectar_responsive_text text_color=\u00bb#333333&#8243; font_size_desktop=\u00bb32px\u00bb font_size_tablet=\u00bb30px\u00bb font_line_height=\u00bb1.2&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb28px\u00bb]\n<h3>3. Otros accesorios de elevaci\u00f3n<\/h3>\n[\/nectar_responsive_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb constrain_group_2=\u00bbyes\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbpadding-2-percent\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Adicionalmente se complement\u00f3 con todo el resto de accesorios de elevaci\u00f3n: Cable de acero con pasacables (una soluci\u00f3n vers\u00e1til y econ\u00f3mica para este rango de capacidades) y Grilletes de Cuerpo Ancho para no da\u00f1ar las eslingas y por tanto no disminuir su capacidad debido a los factores de reducci\u00f3n de capacidad que se aplicar\u00edan en caso de utilizar grilletes convencionales.<\/p>\n<p>La gesti\u00f3n para conseguir todos los accesorios tambi\u00e9n tenemos que agradecerla al buen trabajo del departamento de compras, ya que no todos los proveedores son capaces de entregar este tipo de accesorios de gran tonelaje en tan poco tiempo.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbleft\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_responsive_text text_color=\u00bb#333333&#8243; font_size_desktop=\u00bb32px\u00bb font_size_tablet=\u00bb30px\u00bb font_line_height=\u00bb1.2&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb28px\u00bb]\n<h3>2. Principales accesorios de elevaci\u00f3n<\/h3>\n[\/nectar_responsive_text][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>La lista completa de accesorios incluye:<\/strong><\/p>\n<p>2 x Grommet sling 6 m x 251 t WLL<br \/>\n2 x Wide body shackles x 300 t WLL<br \/>\n1 x Spreader beam OX-SB-250\/400 x 5 m span<br \/>\n2 x Wide body shackles x 200 t WLL<br \/>\n4 x Grommet sling 4 m x 134 t WLL<br \/>\n4 x Wide body shackles x 125 t WLL<br \/>\n2 x Spreader beam OX-SB-170 x 4 m span<br \/>\n4 x Wide body shackles x 125 t WLL<b><br \/>\n<strong>2 x Dyneema slings x 12 m x 100 t WLL\/each<\/strong><\/b>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbtop\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb3%\u00bb bottom_padding=\u00bb6%\u00bb left_padding_desktop=\u00bb5%\u00bb constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbno-extra-padding\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][nectar_responsive_text text_color=\u00bb#333333&#8243; font_size_desktop=\u00bb32px\u00bb font_size_tablet=\u00bb30px\u00bb font_line_height=\u00bb1.2&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb28px\u00bb]\n<h3>4. Proyecto realizado<\/h3>\n[\/nectar_responsive_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb constrain_group_2=\u00bbyes\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbpadding-2-percent\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<ul>\n<li><strong>Gesti\u00f3n log\u00edstica<\/strong>: Gracias a una eficaz coordinaci\u00f3n por parte del departamento de compras, conseguimos concertar la entrega de todos los accesorios necesarios en un tiempo r\u00e9cord, superando las limitaciones de los proveedores.<\/li>\n<li><strong>Ejecuci\u00f3n y entrega<\/strong>: Realizamos la ingenier\u00eda de elevaci\u00f3n, elaboramos los planos, reunimos los materiales y los entregamos en las instalaciones del cliente, todo ello sin descuidar otros pedidos en curso.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbleft\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-31497\" src=\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/10\/Gruas_Aguilar_Desmontaje_Puente_Nudo_M30_7.jpg\" alt=\"\" width=\"2000\" height=\"1124\" srcset=\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/10\/Gruas_Aguilar_Desmontaje_Puente_Nudo_M30_7.jpg 2000w, https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/10\/Gruas_Aguilar_Desmontaje_Puente_Nudo_M30_7-300x169.jpg 300w, https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/10\/Gruas_Aguilar_Desmontaje_Puente_Nudo_M30_7-1024x575.jpg 1024w, https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/10\/Gruas_Aguilar_Desmontaje_Puente_Nudo_M30_7-768x432.jpg 768w, https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/10\/Gruas_Aguilar_Desmontaje_Puente_Nudo_M30_7-1536x863.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#004893&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb3%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb3%\u00bb top_margin=\u00bb0&#8243; constrain_group_7=\u00bbyes\u00bb bottom_margin=\u00bb0&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][image_with_animation image_url=\u00bb30446&#8243; image_size=\u00bbmedium\u00bb animation_type=\u00bbentrance\u00bb animation=\u00bbNone\u00bb animation_movement_type=\u00bbtransform_y\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb][\/vc_column][vc_column column_padding=\u00bbpadding-4-percent\u00bb column_padding_tablet=\u00bbpadding-2-percent\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb constrain_group_2=\u00bbyes\u00bb constrain_group_4=\u00bbyes\u00bb left_margin_phone=\u00bb0&#8243; constrain_group_6=\u00bbyes\u00bb right_margin_phone=\u00bb0&#8243; column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][nectar_responsive_text text_color=\u00bb#ffffff\u00bb font_size_desktop=\u00bb30px\u00bb font_size_tablet=\u00bb28px\u00bb font_line_height=\u00bb1.3&#8243; text_direction=\u00bbdefault\u00bb font_size_phone=\u00bb26px\u00bb]Si necesita m\u00e1s informaci\u00f3n sobre los Balancines Separadores, puede consultar nuestra p\u00e1gina de productos.[\/nectar_responsive_text][nectar_cta btn_style=\u00bbarrow-animation\u00bb heading_tag=\u00bbh4&#8243; button_color=\u00bbextra-color-1&#8243; button_color_hover=\u00bb#ffffff\u00bb text_color=\u00bb#ffffff\u00bb text_color_hover=\u00bb#ff3b00&#8243; button_border_thickness=\u00bb0px\u00bb link_type=\u00bbnew_tab\u00bb alignment=\u00bbleft\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb constrain_group_3=\u00bbyes\u00bb constrain_group_4=\u00bbyes\u00bb display=\u00bbblock\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb link_text=\u00bbVer Balanc\u00edn Separador Modular\u00bb padding_top=\u00bb10&#8243; padding_right=\u00bb20&#8243; padding_bottom=\u00bb10&#8243; padding_left=\u00bb20&#8243; margin_bottom=\u00bb20&#8243; font_size_desktop=\u00bb20PX\u00bb url=\u00bbhttps:\/\/ox-rud.com\/es\/productos\/balancin-de-carga-para-gruas\/\u00bb][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb0&#8243; bottom_padding=\u00bb6%\u00bb left_padding_desktop=\u00bb5%\u00bb constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbpadding-10-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb&#8230;<\/p>\n","protected":false},"author":2,"featured_media":31568,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,107,109],"tags":[],"class_list":{"0":"post-31501","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-spreader-beam-es","8":"category-obra-publica","9":"category-proyectos-especiales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuestro Balanc\u00edn de carga Multipuntos en el Campo del Bar\u00e7a<\/title>\n<meta name=\"description\" content=\"Contentos de salir en los principales peri\u00f3dicos deportivos del pa\u00eds con el Balanc\u00edn de Carga Multitaladro, en las obras del Camp Nou.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestro Balanc\u00edn de carga Multipuntos en el Campo del Bar\u00e7a\" \/>\n<meta property=\"og:description\" content=\"Contentos de salir en los principales peri\u00f3dicos deportivos del pa\u00eds con el Balanc\u00edn de Carga Multitaladro, en las obras del Camp Nou.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"OX &amp; RUD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/twitter.com\/OxWorldwide\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-23T21:14:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T08:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Isabel Cont\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabel Cont\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ox-rud.com\/es\/nuestro-balancin-separador-modular-m30-madrid\/\"},\"author\":{\"name\":\"Isabel Cont\u00edn\",\"@id\":\"https:\/\/ox-rud.com\/es\/#\/schema\/person\/0a47ea10ec6ac1a282d02eaeedff3c82\"},\"headline\":\"Nuestro Balanc\u00edn Separador Modular en la M30 en Madrid\",\"datePublished\":\"2024-06-23T21:14:17+00:00\",\"dateModified\":\"2025-11-20T08:25:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ox-rud.com\/es\/nuestro-balancin-separador-modular-m30-madrid\/\"},\"wordCount\":4740,\"publisher\":{\"@id\":\"https:\/\/ox-rud.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp\",\"articleSection\":[\"Balanc\u00edn Separador Modular\",\"Obra P\u00fablica\",\"Proyectos Especiales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ox-rud.com\/es\/nuestro-balancin-separador-modular-m30-madrid\/\",\"url\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/\",\"name\":\"Nuestro Balanc\u00edn de carga Multipuntos en el Campo del Bar\u00e7a\",\"isPartOf\":{\"@id\":\"https:\/\/ox-rud.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp\",\"datePublished\":\"2024-06-23T21:14:17+00:00\",\"dateModified\":\"2025-11-20T08:25:14+00:00\",\"description\":\"Contentos de salir en los principales peri\u00f3dicos deportivos del pa\u00eds con el Balanc\u00edn de Carga Multitaladro, en las obras del Camp Nou.\",\"breadcrumb\":{\"@id\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage\",\"url\":\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp\",\"contentUrl\":\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ox-rud.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestro Balanc\u00edn Separador Modular en la M30 en Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ox-rud.com\/es\/#website\",\"url\":\"https:\/\/ox-rud.com\/es\/\",\"name\":\"OX & RUD\",\"description\":\"Equipos de Elevaci\u00f3n de Cargas\",\"publisher\":{\"@id\":\"https:\/\/ox-rud.com\/es\/#organization\"},\"alternateName\":\"OX & RUD\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ox-rud.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ox-rud.com\/es\/#organization\",\"name\":\"OX & RUD\",\"url\":\"https:\/\/ox-rud.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ox-rud.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/05\/Logo-OXRUD-web-no-retina-colour.png\",\"contentUrl\":\"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/05\/Logo-OXRUD-web-no-retina-colour.png\",\"width\":300,\"height\":62,\"caption\":\"OX & RUD\"},\"image\":{\"@id\":\"https:\/\/ox-rud.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/twitter.com\/OxWorldwide\",\"https:\/\/www.linkedin.com\/company\/ox-worldwide\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ox-rud.com\/es\/#\/schema\/person\/0a47ea10ec6ac1a282d02eaeedff3c82\",\"name\":\"Isabel Cont\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ox-rud.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/92a24bdf6a0e869f0bff023bc38e3b71d4746d702971af5f212458fa03deb854?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/92a24bdf6a0e869f0bff023bc38e3b71d4746d702971af5f212458fa03deb854?s=96&d=mm&r=g\",\"caption\":\"Isabel Cont\u00edn\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestro Balanc\u00edn de carga Multipuntos en el Campo del Bar\u00e7a","description":"Contentos de salir en los principales peri\u00f3dicos deportivos del pa\u00eds con el Balanc\u00edn de Carga Multitaladro, en las obras del Camp Nou.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Nuestro Balanc\u00edn de carga Multipuntos en el Campo del Bar\u00e7a","og_description":"Contentos de salir en los principales peri\u00f3dicos deportivos del pa\u00eds con el Balanc\u00edn de Carga Multitaladro, en las obras del Camp Nou.","og_url":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/","og_site_name":"OX &amp; RUD","article_publisher":"https:\/\/twitter.com\/OxWorldwide","article_published_time":"2024-06-23T21:14:17+00:00","article_modified_time":"2025-11-20T08:25:14+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp","type":"image\/webp"}],"author":"Isabel Cont\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Isabel Cont\u00edn","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#article","isPartOf":{"@id":"https:\/\/ox-rud.com\/es\/nuestro-balancin-separador-modular-m30-madrid\/"},"author":{"name":"Isabel Cont\u00edn","@id":"https:\/\/ox-rud.com\/es\/#\/schema\/person\/0a47ea10ec6ac1a282d02eaeedff3c82"},"headline":"Nuestro Balanc\u00edn Separador Modular en la M30 en Madrid","datePublished":"2024-06-23T21:14:17+00:00","dateModified":"2025-11-20T08:25:14+00:00","mainEntityOfPage":{"@id":"https:\/\/ox-rud.com\/es\/nuestro-balancin-separador-modular-m30-madrid\/"},"wordCount":4740,"publisher":{"@id":"https:\/\/ox-rud.com\/es\/#organization"},"image":{"@id":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp","articleSection":["Balanc\u00edn Separador Modular","Obra P\u00fablica","Proyectos Especiales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ox-rud.com\/es\/nuestro-balancin-separador-modular-m30-madrid\/","url":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/","name":"Nuestro Balanc\u00edn de carga Multipuntos en el Campo del Bar\u00e7a","isPartOf":{"@id":"https:\/\/ox-rud.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage"},"image":{"@id":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp","datePublished":"2024-06-23T21:14:17+00:00","dateModified":"2025-11-20T08:25:14+00:00","description":"Contentos de salir en los principales peri\u00f3dicos deportivos del pa\u00eds con el Balanc\u00edn de Carga Multitaladro, en las obras del Camp Nou.","breadcrumb":{"@id":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#primaryimage","url":"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp","contentUrl":"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/12\/Balancines_de_carga_para_gruas_4-1.webp","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/ox-rud.com\/es\/balancin-separador-construccion-puente-m30-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ox-rud.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nuestro Balanc\u00edn Separador Modular en la M30 en Madrid"}]},{"@type":"WebSite","@id":"https:\/\/ox-rud.com\/es\/#website","url":"https:\/\/ox-rud.com\/es\/","name":"OX & RUD","description":"Equipos de Elevaci\u00f3n de Cargas","publisher":{"@id":"https:\/\/ox-rud.com\/es\/#organization"},"alternateName":"OX & RUD","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ox-rud.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ox-rud.com\/es\/#organization","name":"OX & RUD","url":"https:\/\/ox-rud.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ox-rud.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/05\/Logo-OXRUD-web-no-retina-colour.png","contentUrl":"https:\/\/ox-rud.com\/wp-content\/uploads\/2024\/05\/Logo-OXRUD-web-no-retina-colour.png","width":300,"height":62,"caption":"OX & RUD"},"image":{"@id":"https:\/\/ox-rud.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/twitter.com\/OxWorldwide","https:\/\/www.linkedin.com\/company\/ox-worldwide\/"]},{"@type":"Person","@id":"https:\/\/ox-rud.com\/es\/#\/schema\/person\/0a47ea10ec6ac1a282d02eaeedff3c82","name":"Isabel Cont\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ox-rud.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/92a24bdf6a0e869f0bff023bc38e3b71d4746d702971af5f212458fa03deb854?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92a24bdf6a0e869f0bff023bc38e3b71d4746d702971af5f212458fa03deb854?s=96&d=mm&r=g","caption":"Isabel Cont\u00edn"}}]}},"_links":{"self":[{"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/posts\/31501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/comments?post=31501"}],"version-history":[{"count":6,"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/posts\/31501\/revisions"}],"predecessor-version":[{"id":31763,"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/posts\/31501\/revisions\/31763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/media\/31568"}],"wp:attachment":[{"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/media?parent=31501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/categories?post=31501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ox-rud.com\/es\/wp-json\/wp\/v2\/tags?post=31501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}